{"id":45207,"date":"2026-02-14T14:40:56","date_gmt":"2026-02-14T14:40:56","guid":{"rendered":"https:\/\/anadolupet.com.tr\/?post_type=product&#038;p=45207"},"modified":"2026-02-23T12:48:32","modified_gmt":"2026-02-23T12:48:32","slug":"flexi-new-classic-l-beden-mavi-5mt-serit-tasma","status":"publish","type":"product","link":"https:\/\/anadolupet.com.tr\/en\/urun\/flexi-new-classic-l-beden-mavi-5mt-serit-tasma\/","title":{"rendered":"Flexi New Classic L Beden Mavi 5MT \u015eerit Tasma"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>50 kg. a\u011f\u0131rl\u0131\u011fa kadar olan k\u00f6pekler i\u00e7in g\u00fcvenle kullan\u0131labilecek, otomatik sarmall\u0131, k\u00f6pek gezdirme tasmas\u0131d\u0131r. * 5 metre uzunlu\u011funda \u015ferit mevcuttur. * Ani duraklatma ve sabitleme yap\u0131labilmekte; bu sayede istenilen uzunlukta kullan\u0131labilmektedir. * Led \u0131\u015f\u0131k sistemi ve Multibox d\u0131\u015fk\u0131 toplama aparat\u0131 ile kullan\u0131labilmektedir. * \u0130\u00e7erisinde 55 cm. uzunlu\u011funda naylon bo\u011fma tasmas\u0131 bulunmaktad\u0131r. * \u00dcr\u00fcn a\u011f\u0131rl\u0131\u011f\u0131: yakla\u015f\u0131k 340 g. * Ba\u011flama ama\u00e7l\u0131 kullan\u0131lmamal\u0131d\u0131r.<\/p>","protected":false},"featured_media":43342,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[2443],"product_tag":[],"class_list":{"0":"post-45207","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-boyun-tasmalari-kopek","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Flexi New Classic L Beden Mavi 5MT \u015eerit Tasma - Anadolu Pet Grup<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/anadolupet.com.tr\/en\/product\/flexi-new-classic-l-beden-mavi-5mt-serit-tasma\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Flexi New Classic L Beden Mavi 5MT \u015eerit Tasma - Anadolu Pet Grup\" \/>\n<meta property=\"og:description\" content=\"50 kg. a\u011f\u0131rl\u0131\u011fa kadar olan k\u00f6pekler i\u00e7in g\u00fcvenle kullan\u0131labilecek, otomatik sarmall\u0131, k\u00f6pek gezdirme tasmas\u0131d\u0131r. * 5 metre uzunlu\u011funda \u015ferit mevcuttur. * Ani duraklatma ve sabitleme yap\u0131labilmekte; bu sayede istenilen uzunlukta kullan\u0131labilmektedir. * Led \u0131\u015f\u0131k sistemi ve Multibox d\u0131\u015fk\u0131 toplama aparat\u0131 ile kullan\u0131labilmektedir. * \u0130\u00e7erisinde 55 cm. uzunlu\u011funda naylon bo\u011fma tasmas\u0131 bulunmaktad\u0131r. * \u00dcr\u00fcn a\u011f\u0131rl\u0131\u011f\u0131: yakla\u015f\u0131k 340 g. * Ba\u011flama ama\u00e7l\u0131 kullan\u0131lmamal\u0131d\u0131r.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/anadolupet.com.tr\/en\/product\/flexi-new-classic-l-beden-mavi-5mt-serit-tasma\/\" \/>\n<meta property=\"og:site_name\" content=\"Anadolu Pet Grup\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-23T12:48:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/anadolupet.com.tr\/wp-content\/uploads\/2026\/02\/235-102009M.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/en\\\/product\\\/flexi-new-classic-l-beden-mavi-5mt-serit-tasma\\\/\",\"url\":\"https:\\\/\\\/anadolupet.com.tr\\\/en\\\/product\\\/flexi-new-classic-l-beden-mavi-5mt-serit-tasma\\\/\",\"name\":\"Flexi New Classic L Beden Mavi 5MT \u015eerit Tasma - Anadolu Pet Grup\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/en\\\/product\\\/flexi-new-classic-l-beden-mavi-5mt-serit-tasma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/en\\\/product\\\/flexi-new-classic-l-beden-mavi-5mt-serit-tasma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/anadolupet.com.tr\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/235-102009M.jpg\",\"datePublished\":\"2026-02-14T14:40:56+00:00\",\"dateModified\":\"2026-02-23T12:48:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/en\\\/product\\\/flexi-new-classic-l-beden-mavi-5mt-serit-tasma\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/anadolupet.com.tr\\\/en\\\/product\\\/flexi-new-classic-l-beden-mavi-5mt-serit-tasma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/en\\\/product\\\/flexi-new-classic-l-beden-mavi-5mt-serit-tasma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/anadolupet.com.tr\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/235-102009M.jpg\",\"contentUrl\":\"https:\\\/\\\/anadolupet.com.tr\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/235-102009M.jpg\",\"width\":750,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/en\\\/product\\\/flexi-new-classic-l-beden-mavi-5mt-serit-tasma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/anadolupet.com.tr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00dcr\u00fcnler\",\"item\":\"https:\\\/\\\/anadolupet.com.tr\\\/urunler\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Flexi New Classic L Beden Mavi 5MT \u015eerit Tasma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/#website\",\"url\":\"https:\\\/\\\/anadolupet.com.tr\\\/\",\"name\":\"Anadolu Pet Grup\",\"description\":\"Her Can\u0131n \u0130yi Ya\u015fam\u0131 \u0130\u00e7in Biraraday\u0131z\",\"publisher\":{\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/anadolupet.com.tr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/#organization\",\"name\":\"Anadolu Pet Grup\",\"alternateName\":\"Anadolu Pet\",\"url\":\"https:\\\/\\\/anadolupet.com.tr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/anadolupet.com.tr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/1614666743370.jpg\",\"contentUrl\":\"https:\\\/\\\/anadolupet.com.tr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/1614666743370.jpg\",\"width\":800,\"height\":571,\"caption\":\"Anadolu Pet Grup\"},\"image\":{\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Flexi New Classic L Beden Mavi 5MT \u015eerit Tasma - Anadolu Pet Grup","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/anadolupet.com.tr\/en\/product\/flexi-new-classic-l-beden-mavi-5mt-serit-tasma\/","og_locale":"en_US","og_type":"article","og_title":"Flexi New Classic L Beden Mavi 5MT \u015eerit Tasma - Anadolu Pet Grup","og_description":"50 kg. a\u011f\u0131rl\u0131\u011fa kadar olan k\u00f6pekler i\u00e7in g\u00fcvenle kullan\u0131labilecek, otomatik sarmall\u0131, k\u00f6pek gezdirme tasmas\u0131d\u0131r. * 5 metre uzunlu\u011funda \u015ferit mevcuttur. * Ani duraklatma ve sabitleme yap\u0131labilmekte; bu sayede istenilen uzunlukta kullan\u0131labilmektedir. * Led \u0131\u015f\u0131k sistemi ve Multibox d\u0131\u015fk\u0131 toplama aparat\u0131 ile kullan\u0131labilmektedir. * \u0130\u00e7erisinde 55 cm. uzunlu\u011funda naylon bo\u011fma tasmas\u0131 bulunmaktad\u0131r. * \u00dcr\u00fcn a\u011f\u0131rl\u0131\u011f\u0131: yakla\u015f\u0131k 340 g. * Ba\u011flama ama\u00e7l\u0131 kullan\u0131lmamal\u0131d\u0131r.","og_url":"https:\/\/anadolupet.com.tr\/en\/product\/flexi-new-classic-l-beden-mavi-5mt-serit-tasma\/","og_site_name":"Anadolu Pet Grup","article_modified_time":"2026-02-23T12:48:32+00:00","og_image":[{"width":750,"height":750,"url":"https:\/\/anadolupet.com.tr\/wp-content\/uploads\/2026\/02\/235-102009M.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/anadolupet.com.tr\/en\/product\/flexi-new-classic-l-beden-mavi-5mt-serit-tasma\/","url":"https:\/\/anadolupet.com.tr\/en\/product\/flexi-new-classic-l-beden-mavi-5mt-serit-tasma\/","name":"Flexi New Classic L Beden Mavi 5MT \u015eerit Tasma - Anadolu Pet Grup","isPartOf":{"@id":"https:\/\/anadolupet.com.tr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/anadolupet.com.tr\/en\/product\/flexi-new-classic-l-beden-mavi-5mt-serit-tasma\/#primaryimage"},"image":{"@id":"https:\/\/anadolupet.com.tr\/en\/product\/flexi-new-classic-l-beden-mavi-5mt-serit-tasma\/#primaryimage"},"thumbnailUrl":"https:\/\/anadolupet.com.tr\/wp-content\/uploads\/2026\/02\/235-102009M.jpg","datePublished":"2026-02-14T14:40:56+00:00","dateModified":"2026-02-23T12:48:32+00:00","breadcrumb":{"@id":"https:\/\/anadolupet.com.tr\/en\/product\/flexi-new-classic-l-beden-mavi-5mt-serit-tasma\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/anadolupet.com.tr\/en\/product\/flexi-new-classic-l-beden-mavi-5mt-serit-tasma\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/anadolupet.com.tr\/en\/product\/flexi-new-classic-l-beden-mavi-5mt-serit-tasma\/#primaryimage","url":"https:\/\/anadolupet.com.tr\/wp-content\/uploads\/2026\/02\/235-102009M.jpg","contentUrl":"https:\/\/anadolupet.com.tr\/wp-content\/uploads\/2026\/02\/235-102009M.jpg","width":750,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/anadolupet.com.tr\/en\/product\/flexi-new-classic-l-beden-mavi-5mt-serit-tasma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/anadolupet.com.tr\/"},{"@type":"ListItem","position":2,"name":"\u00dcr\u00fcnler","item":"https:\/\/anadolupet.com.tr\/urunler\/"},{"@type":"ListItem","position":3,"name":"Flexi New Classic L Beden Mavi 5MT \u015eerit Tasma"}]},{"@type":"WebSite","@id":"https:\/\/anadolupet.com.tr\/#website","url":"https:\/\/anadolupet.com.tr\/","name":"Anadolu Pet Group","description":"We Stand Together for the Well-Being of Every Life","publisher":{"@id":"https:\/\/anadolupet.com.tr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/anadolupet.com.tr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/anadolupet.com.tr\/#organization","name":"Anadolu Pet Group","alternateName":"Anadolu Pet","url":"https:\/\/anadolupet.com.tr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/anadolupet.com.tr\/#\/schema\/logo\/image\/","url":"https:\/\/anadolupet.com.tr\/wp-content\/uploads\/2026\/03\/1614666743370.jpg","contentUrl":"https:\/\/anadolupet.com.tr\/wp-content\/uploads\/2026\/03\/1614666743370.jpg","width":800,"height":571,"caption":"Anadolu Pet Grup"},"image":{"@id":"https:\/\/anadolupet.com.tr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/anadolupet.com.tr\/en\/wp-json\/wp\/v2\/product\/45207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anadolupet.com.tr\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/anadolupet.com.tr\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/anadolupet.com.tr\/en\/wp-json\/wp\/v2\/comments?post=45207"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anadolupet.com.tr\/en\/wp-json\/wp\/v2\/media\/43342"}],"wp:attachment":[{"href":"https:\/\/anadolupet.com.tr\/en\/wp-json\/wp\/v2\/media?parent=45207"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/anadolupet.com.tr\/en\/wp-json\/wp\/v2\/product_brand?post=45207"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/anadolupet.com.tr\/en\/wp-json\/wp\/v2\/product_cat?post=45207"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/anadolupet.com.tr\/en\/wp-json\/wp\/v2\/product_tag?post=45207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}