{"id":46085,"date":"2026-02-14T14:45:41","date_gmt":"2026-02-14T14:45:41","guid":{"rendered":"https:\/\/anadolupet.com.tr\/?post_type=product&#038;p=46085"},"modified":"2026-02-23T12:51:44","modified_gmt":"2026-02-23T12:51:44","slug":"schesir-jelly-ton-baligi-jole-icinde-yetiskin-kedi-konservesi-multipack-6x50g","status":"publish","type":"product","link":"https:\/\/anadolupet.com.tr\/en\/urun\/schesir-jelly-ton-baligi-jole-icinde-yetiskin-kedi-konservesi-multipack-6x50g\/","title":{"rendered":"Schesir Jelly Ton Bal\u0131\u011f\u0131 J\u00f6le \u0130\u00e7inde Yeti\u015fkin Kedi Konservesi Multipack 6x50g"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>\u0130\u00e7indekiler: %52 Ton bal\u0131\u011f\u0131, %1.5 pirin\u00e7<br \/>\nAnalitik Bile\u015fenler: Protein %12, ham s\u0131v\u0131 ya\u011f ve kat\u0131 ya\u011flar %1.5, ham sel\u00fcloz %0.5, ham k\u00fcl %1, nem %85<br \/>\nOda s\u0131cakl\u0131\u011f\u0131nda servis ediniz. A\u00e7\u0131ld\u0131\u011f\u0131nda, buzdolab\u0131nda muhafaza ediniz ve 48 saat i\u00e7erisinde bitiriniz.<br \/>\nG\u00fcnde 2 kutuya kadar servis edebilirsiniz.<br \/>\nTam ya\u015f ve\/veya Schesir kuru mama ile birlikte servis ediniz.<\/p>","protected":false},"featured_media":43196,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[2427],"product_tag":[],"class_list":["post-46085","product","type-product","status-publish","has-post-thumbnail","product_cat-kedi-konserveleri","first","instock","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Schesir Jelly Ton Bal\u0131\u011f\u0131 J\u00f6le \u0130\u00e7inde Yeti\u015fkin Kedi Konservesi Multipack 6x50g - Anadolu Pet Grup<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/anadolupet.com.tr\/en\/product\/schesir-jelly-ton-baligi-jole-icinde-yetiskin-kedi-konservesi-multipack-6x50g\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schesir Jelly Ton Bal\u0131\u011f\u0131 J\u00f6le \u0130\u00e7inde Yeti\u015fkin Kedi Konservesi Multipack 6x50g - Anadolu Pet Grup\" \/>\n<meta property=\"og:description\" content=\"\u0130\u00e7indekiler: %52 Ton bal\u0131\u011f\u0131, %1.5 pirin\u00e7 Analitik Bile\u015fenler: Protein %12, ham s\u0131v\u0131 ya\u011f ve kat\u0131 ya\u011flar %1.5, ham sel\u00fcloz %0.5, ham k\u00fcl %1, nem %85 Oda s\u0131cakl\u0131\u011f\u0131nda servis ediniz. A\u00e7\u0131ld\u0131\u011f\u0131nda, buzdolab\u0131nda muhafaza ediniz ve 48 saat i\u00e7erisinde bitiriniz. G\u00fcnde 2 kutuya kadar servis edebilirsiniz. Tam ya\u015f ve\/veya Schesir kuru mama ile birlikte servis ediniz.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/anadolupet.com.tr\/en\/product\/schesir-jelly-ton-baligi-jole-icinde-yetiskin-kedi-konservesi-multipack-6x50g\/\" \/>\n<meta property=\"og:site_name\" content=\"Anadolu Pet Grup\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-23T12:51:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/anadolupet.com.tr\/wp-content\/uploads\/2026\/02\/230-C100.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/urun\\\/schesir-jelly-ton-baligi-jole-icinde-yetiskin-kedi-konservesi-multipack-6x50g\\\/\",\"url\":\"https:\\\/\\\/anadolupet.com.tr\\\/urun\\\/schesir-jelly-ton-baligi-jole-icinde-yetiskin-kedi-konservesi-multipack-6x50g\\\/\",\"name\":\"Schesir Jelly Ton Bal\u0131\u011f\u0131 J\u00f6le \u0130\u00e7inde Yeti\u015fkin Kedi Konservesi Multipack 6x50g - Anadolu Pet Grup\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/urun\\\/schesir-jelly-ton-baligi-jole-icinde-yetiskin-kedi-konservesi-multipack-6x50g\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/urun\\\/schesir-jelly-ton-baligi-jole-icinde-yetiskin-kedi-konservesi-multipack-6x50g\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/anadolupet.com.tr\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/230-C100.jpg\",\"datePublished\":\"2026-02-14T14:45:41+00:00\",\"dateModified\":\"2026-02-23T12:51:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/urun\\\/schesir-jelly-ton-baligi-jole-icinde-yetiskin-kedi-konservesi-multipack-6x50g\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/anadolupet.com.tr\\\/urun\\\/schesir-jelly-ton-baligi-jole-icinde-yetiskin-kedi-konservesi-multipack-6x50g\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/urun\\\/schesir-jelly-ton-baligi-jole-icinde-yetiskin-kedi-konservesi-multipack-6x50g\\\/#primaryimage\",\"url\":\"https:\\\/\\\/anadolupet.com.tr\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/230-C100.jpg\",\"contentUrl\":\"https:\\\/\\\/anadolupet.com.tr\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/230-C100.jpg\",\"width\":750,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/urun\\\/schesir-jelly-ton-baligi-jole-icinde-yetiskin-kedi-konservesi-multipack-6x50g\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/anadolupet.com.tr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00dcr\u00fcnler\",\"item\":\"https:\\\/\\\/anadolupet.com.tr\\\/urunler\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Schesir Jelly Ton Bal\u0131\u011f\u0131 J\u00f6le \u0130\u00e7inde Yeti\u015fkin Kedi Konservesi Multipack 6x50g\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/#website\",\"url\":\"https:\\\/\\\/anadolupet.com.tr\\\/\",\"name\":\"Anadolu Pet Grup\",\"description\":\"Her Can\u0131n \u0130yi Ya\u015fam\u0131 \u0130\u00e7in Biraraday\u0131z\",\"publisher\":{\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/anadolupet.com.tr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/#organization\",\"name\":\"Anadolu Pet Grup\",\"alternateName\":\"Anadolu Pet\",\"url\":\"https:\\\/\\\/anadolupet.com.tr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/anadolupet.com.tr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/1614666743370.jpg\",\"contentUrl\":\"https:\\\/\\\/anadolupet.com.tr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/1614666743370.jpg\",\"width\":800,\"height\":571,\"caption\":\"Anadolu Pet Grup\"},\"image\":{\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schesir Jelly Ton Bal\u0131\u011f\u0131 J\u00f6le \u0130\u00e7inde Yeti\u015fkin Kedi Konservesi Multipack 6x50g - Anadolu Pet Grup","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/anadolupet.com.tr\/en\/product\/schesir-jelly-ton-baligi-jole-icinde-yetiskin-kedi-konservesi-multipack-6x50g\/","og_locale":"en_US","og_type":"article","og_title":"Schesir Jelly Ton Bal\u0131\u011f\u0131 J\u00f6le \u0130\u00e7inde Yeti\u015fkin Kedi Konservesi Multipack 6x50g - Anadolu Pet Grup","og_description":"\u0130\u00e7indekiler: %52 Ton bal\u0131\u011f\u0131, %1.5 pirin\u00e7 Analitik Bile\u015fenler: Protein %12, ham s\u0131v\u0131 ya\u011f ve kat\u0131 ya\u011flar %1.5, ham sel\u00fcloz %0.5, ham k\u00fcl %1, nem %85 Oda s\u0131cakl\u0131\u011f\u0131nda servis ediniz. A\u00e7\u0131ld\u0131\u011f\u0131nda, buzdolab\u0131nda muhafaza ediniz ve 48 saat i\u00e7erisinde bitiriniz. G\u00fcnde 2 kutuya kadar servis edebilirsiniz. Tam ya\u015f ve\/veya Schesir kuru mama ile birlikte servis ediniz.","og_url":"https:\/\/anadolupet.com.tr\/en\/product\/schesir-jelly-ton-baligi-jole-icinde-yetiskin-kedi-konservesi-multipack-6x50g\/","og_site_name":"Anadolu Pet Grup","article_modified_time":"2026-02-23T12:51:44+00:00","og_image":[{"width":750,"height":750,"url":"https:\/\/anadolupet.com.tr\/wp-content\/uploads\/2026\/02\/230-C100.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/anadolupet.com.tr\/urun\/schesir-jelly-ton-baligi-jole-icinde-yetiskin-kedi-konservesi-multipack-6x50g\/","url":"https:\/\/anadolupet.com.tr\/urun\/schesir-jelly-ton-baligi-jole-icinde-yetiskin-kedi-konservesi-multipack-6x50g\/","name":"Schesir Jelly Ton Bal\u0131\u011f\u0131 J\u00f6le \u0130\u00e7inde Yeti\u015fkin Kedi Konservesi Multipack 6x50g - Anadolu Pet Grup","isPartOf":{"@id":"https:\/\/anadolupet.com.tr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/anadolupet.com.tr\/urun\/schesir-jelly-ton-baligi-jole-icinde-yetiskin-kedi-konservesi-multipack-6x50g\/#primaryimage"},"image":{"@id":"https:\/\/anadolupet.com.tr\/urun\/schesir-jelly-ton-baligi-jole-icinde-yetiskin-kedi-konservesi-multipack-6x50g\/#primaryimage"},"thumbnailUrl":"https:\/\/anadolupet.com.tr\/wp-content\/uploads\/2026\/02\/230-C100.jpg","datePublished":"2026-02-14T14:45:41+00:00","dateModified":"2026-02-23T12:51:44+00:00","breadcrumb":{"@id":"https:\/\/anadolupet.com.tr\/urun\/schesir-jelly-ton-baligi-jole-icinde-yetiskin-kedi-konservesi-multipack-6x50g\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/anadolupet.com.tr\/urun\/schesir-jelly-ton-baligi-jole-icinde-yetiskin-kedi-konservesi-multipack-6x50g\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/anadolupet.com.tr\/urun\/schesir-jelly-ton-baligi-jole-icinde-yetiskin-kedi-konservesi-multipack-6x50g\/#primaryimage","url":"https:\/\/anadolupet.com.tr\/wp-content\/uploads\/2026\/02\/230-C100.jpg","contentUrl":"https:\/\/anadolupet.com.tr\/wp-content\/uploads\/2026\/02\/230-C100.jpg","width":750,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/anadolupet.com.tr\/urun\/schesir-jelly-ton-baligi-jole-icinde-yetiskin-kedi-konservesi-multipack-6x50g\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/anadolupet.com.tr\/"},{"@type":"ListItem","position":2,"name":"\u00dcr\u00fcnler","item":"https:\/\/anadolupet.com.tr\/urunler\/"},{"@type":"ListItem","position":3,"name":"Schesir Jelly Ton Bal\u0131\u011f\u0131 J\u00f6le \u0130\u00e7inde Yeti\u015fkin Kedi Konservesi Multipack 6x50g"}]},{"@type":"WebSite","@id":"https:\/\/anadolupet.com.tr\/#website","url":"https:\/\/anadolupet.com.tr\/","name":"Anadolu Pet Group","description":"We Stand Together for the Well-Being of Every Life","publisher":{"@id":"https:\/\/anadolupet.com.tr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/anadolupet.com.tr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/anadolupet.com.tr\/#organization","name":"Anadolu Pet Group","alternateName":"Anadolu Pet","url":"https:\/\/anadolupet.com.tr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/anadolupet.com.tr\/#\/schema\/logo\/image\/","url":"https:\/\/anadolupet.com.tr\/wp-content\/uploads\/2026\/03\/1614666743370.jpg","contentUrl":"https:\/\/anadolupet.com.tr\/wp-content\/uploads\/2026\/03\/1614666743370.jpg","width":800,"height":571,"caption":"Anadolu Pet Grup"},"image":{"@id":"https:\/\/anadolupet.com.tr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/anadolupet.com.tr\/en\/wp-json\/wp\/v2\/product\/46085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anadolupet.com.tr\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/anadolupet.com.tr\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/anadolupet.com.tr\/en\/wp-json\/wp\/v2\/comments?post=46085"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anadolupet.com.tr\/en\/wp-json\/wp\/v2\/media\/43196"}],"wp:attachment":[{"href":"https:\/\/anadolupet.com.tr\/en\/wp-json\/wp\/v2\/media?parent=46085"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/anadolupet.com.tr\/en\/wp-json\/wp\/v2\/product_brand?post=46085"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/anadolupet.com.tr\/en\/wp-json\/wp\/v2\/product_cat?post=46085"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/anadolupet.com.tr\/en\/wp-json\/wp\/v2\/product_tag?post=46085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}