{"id":3841,"count":8,"description":"","link":"https:\/\/anadolupet.com.tr\/en\/urun-kategori\/kedi\/receteli-diyet-kedi-mamalari-kedi\/","name":"Re\u00e7eteli D\u0130yet Kedi Mamalar\u0131","slug":"receteli-diyet-kedi-mamalari-kedi","taxonomy":"product_cat","parent":2373,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Re\u00e7eteli D\u0130yet Kedi Mamalar\u0131 ar\u015fivleri - Anadolu Pet Grup<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/anadolupet.com.tr\/en\/product-category\/cat\/receteli-diyet-kedi-mamalari-kedi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Re\u00e7eteli D\u0130yet Kedi Mamalar\u0131 ar\u015fivleri - Anadolu Pet Grup\" \/>\n<meta property=\"og:url\" content=\"https:\/\/anadolupet.com.tr\/en\/product-category\/cat\/receteli-diyet-kedi-mamalari-kedi\/\" \/>\n<meta property=\"og:site_name\" content=\"Anadolu Pet Grup\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/urun-kategori\\\/kedi\\\/receteli-diyet-kedi-mamalari-kedi\\\/\",\"url\":\"https:\\\/\\\/anadolupet.com.tr\\\/urun-kategori\\\/kedi\\\/receteli-diyet-kedi-mamalari-kedi\\\/\",\"name\":\"Re\u00e7eteli D\u0130yet Kedi Mamalar\u0131 ar\u015fivleri - Anadolu Pet Grup\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/urun-kategori\\\/kedi\\\/receteli-diyet-kedi-mamalari-kedi\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/urun-kategori\\\/kedi\\\/receteli-diyet-kedi-mamalari-kedi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/anadolupet.com.tr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kedi\",\"item\":\"https:\\\/\\\/anadolupet.com.tr\\\/en\\\/product-category\\\/cat\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Re\u00e7eteli D\u0130yet Kedi Mamalar\u0131\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/#website\",\"url\":\"https:\\\/\\\/anadolupet.com.tr\\\/\",\"name\":\"Anadolu Pet Grup\",\"description\":\"Her Can\u0131n \u0130yi Ya\u015fam\u0131 \u0130\u00e7in Biraraday\u0131z\",\"publisher\":{\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/anadolupet.com.tr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/#organization\",\"name\":\"Anadolu Pet Grup\",\"alternateName\":\"Anadolu Pet\",\"url\":\"https:\\\/\\\/anadolupet.com.tr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/anadolupet.com.tr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/1614666743370.jpg\",\"contentUrl\":\"https:\\\/\\\/anadolupet.com.tr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/1614666743370.jpg\",\"width\":800,\"height\":571,\"caption\":\"Anadolu Pet Grup\"},\"image\":{\"@id\":\"https:\\\/\\\/anadolupet.com.tr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Re\u00e7eteli D\u0130yet Kedi Mamalar\u0131 ar\u015fivleri - Anadolu Pet Grup","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/anadolupet.com.tr\/en\/product-category\/cat\/receteli-diyet-kedi-mamalari-kedi\/","og_locale":"en_US","og_type":"article","og_title":"Re\u00e7eteli D\u0130yet Kedi Mamalar\u0131 ar\u015fivleri - Anadolu Pet Grup","og_url":"https:\/\/anadolupet.com.tr\/en\/product-category\/cat\/receteli-diyet-kedi-mamalari-kedi\/","og_site_name":"Anadolu Pet Grup","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/anadolupet.com.tr\/urun-kategori\/kedi\/receteli-diyet-kedi-mamalari-kedi\/","url":"https:\/\/anadolupet.com.tr\/urun-kategori\/kedi\/receteli-diyet-kedi-mamalari-kedi\/","name":"Re\u00e7eteli D\u0130yet Kedi Mamalar\u0131 ar\u015fivleri - Anadolu Pet Grup","isPartOf":{"@id":"https:\/\/anadolupet.com.tr\/#website"},"breadcrumb":{"@id":"https:\/\/anadolupet.com.tr\/urun-kategori\/kedi\/receteli-diyet-kedi-mamalari-kedi\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/anadolupet.com.tr\/urun-kategori\/kedi\/receteli-diyet-kedi-mamalari-kedi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/anadolupet.com.tr\/"},{"@type":"ListItem","position":2,"name":"Kedi","item":"https:\/\/anadolupet.com.tr\/en\/product-category\/cat\/"},{"@type":"ListItem","position":3,"name":"Re\u00e7eteli D\u0130yet Kedi Mamalar\u0131"}]},{"@type":"WebSite","@id":"https:\/\/anadolupet.com.tr\/#website","url":"https:\/\/anadolupet.com.tr\/","name":"Anadolu Pet Group","description":"We Stand Together for the Well-Being of Every Life","publisher":{"@id":"https:\/\/anadolupet.com.tr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/anadolupet.com.tr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/anadolupet.com.tr\/#organization","name":"Anadolu Pet Group","alternateName":"Anadolu Pet","url":"https:\/\/anadolupet.com.tr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/anadolupet.com.tr\/#\/schema\/logo\/image\/","url":"https:\/\/anadolupet.com.tr\/wp-content\/uploads\/2026\/03\/1614666743370.jpg","contentUrl":"https:\/\/anadolupet.com.tr\/wp-content\/uploads\/2026\/03\/1614666743370.jpg","width":800,"height":571,"caption":"Anadolu Pet Grup"},"image":{"@id":"https:\/\/anadolupet.com.tr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/anadolupet.com.tr\/en\/wp-json\/wp\/v2\/product_cat\/3841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anadolupet.com.tr\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/anadolupet.com.tr\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/anadolupet.com.tr\/en\/wp-json\/wp\/v2\/product_cat\/2373"}],"wp:post_type":[{"href":"https:\/\/anadolupet.com.tr\/en\/wp-json\/wp\/v2\/product?product_cat=3841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}